{"id":4274,"date":"2024-02-01T15:25:58","date_gmt":"2024-02-01T15:25:58","guid":{"rendered":"https:\/\/aep61-74.org\/?p=4274"},"modified":"2026-05-05T11:16:58","modified_gmt":"2026-05-05T11:16:58","slug":"a-passos-da-liberdade","status":"publish","type":"post","link":"https:\/\/aep61-74.org\/index.php\/2024\/02\/01\/a-passos-da-liberdade\/","title":{"rendered":"A Passos da Liberdade"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"725\" height=\"1024\" src=\"https:\/\/aep61-74.org\/wp-content\/uploads\/2024\/02\/A-Passos-da-Liberdade2-725x1024.jpg\" alt=\"\" class=\"wp-image-4279\" srcset=\"https:\/\/aep61-74.org\/wp-content\/uploads\/2024\/02\/A-Passos-da-Liberdade2-725x1024.jpg 725w, https:\/\/aep61-74.org\/wp-content\/uploads\/2024\/02\/A-Passos-da-Liberdade2-212x300.jpg 212w, https:\/\/aep61-74.org\/wp-content\/uploads\/2024\/02\/A-Passos-da-Liberdade2-768x1084.jpg 768w, https:\/\/aep61-74.org\/wp-content\/uploads\/2024\/02\/A-Passos-da-Liberdade2.jpg 1029w\" sizes=\"auto, (max-width: 725px) 100vw, 725px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"722\" height=\"1024\" src=\"https:\/\/aep61-74.org\/wp-content\/uploads\/2024\/02\/A-Passos-da-Liberdade3-722x1024.jpg\" alt=\"\" class=\"wp-image-4280\" srcset=\"https:\/\/aep61-74.org\/wp-content\/uploads\/2024\/02\/A-Passos-da-Liberdade3-722x1024.jpg 722w, https:\/\/aep61-74.org\/wp-content\/uploads\/2024\/02\/A-Passos-da-Liberdade3-212x300.jpg 212w, https:\/\/aep61-74.org\/wp-content\/uploads\/2024\/02\/A-Passos-da-Liberdade3-768x1089.jpg 768w, https:\/\/aep61-74.org\/wp-content\/uploads\/2024\/02\/A-Passos-da-Liberdade3.jpg 1016w\" sizes=\"auto, (max-width: 722px) 100vw, 722px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"1024\" src=\"https:\/\/aep61-74.org\/wp-content\/uploads\/2024\/02\/A-Passos-da-Liberdade4-720x1024.jpg\" alt=\"\" class=\"wp-image-4281\" srcset=\"https:\/\/aep61-74.org\/wp-content\/uploads\/2024\/02\/A-Passos-da-Liberdade4-720x1024.jpg 720w, https:\/\/aep61-74.org\/wp-content\/uploads\/2024\/02\/A-Passos-da-Liberdade4-211x300.jpg 211w, https:\/\/aep61-74.org\/wp-content\/uploads\/2024\/02\/A-Passos-da-Liberdade4-768x1093.jpg 768w, https:\/\/aep61-74.org\/wp-content\/uploads\/2024\/02\/A-Passos-da-Liberdade4.jpg 1012w\" sizes=\"auto, (max-width: 720px) 100vw, 720px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"722\" height=\"1024\" src=\"https:\/\/aep61-74.org\/wp-content\/uploads\/2024\/02\/A-Passos-da-Liberdade5-722x1024.jpg\" alt=\"\" class=\"wp-image-4282\" srcset=\"https:\/\/aep61-74.org\/wp-content\/uploads\/2024\/02\/A-Passos-da-Liberdade5-722x1024.jpg 722w, https:\/\/aep61-74.org\/wp-content\/uploads\/2024\/02\/A-Passos-da-Liberdade5-212x300.jpg 212w, https:\/\/aep61-74.org\/wp-content\/uploads\/2024\/02\/A-Passos-da-Liberdade5-768x1089.jpg 768w, https:\/\/aep61-74.org\/wp-content\/uploads\/2024\/02\/A-Passos-da-Liberdade5.jpg 1016w\" sizes=\"auto, (max-width: 722px) 100vw, 722px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\"><\/div>","protected":false},"author":1,"featured_media":4275,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[243],"tags":[],"class_list":{"0":"post-4274","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-informacoes"},"_links":{"self":[{"href":"https:\/\/aep61-74.org\/index.php\/wp-json\/wp\/v2\/posts\/4274","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aep61-74.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aep61-74.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aep61-74.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/aep61-74.org\/index.php\/wp-json\/wp\/v2\/comments?post=4274"}],"version-history":[{"count":2,"href":"https:\/\/aep61-74.org\/index.php\/wp-json\/wp\/v2\/posts\/4274\/revisions"}],"predecessor-version":[{"id":4283,"href":"https:\/\/aep61-74.org\/index.php\/wp-json\/wp\/v2\/posts\/4274\/revisions\/4283"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aep61-74.org\/index.php\/wp-json\/wp\/v2\/media\/4275"}],"wp:attachment":[{"href":"https:\/\/aep61-74.org\/index.php\/wp-json\/wp\/v2\/media?parent=4274"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aep61-74.org\/index.php\/wp-json\/wp\/v2\/categories?post=4274"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aep61-74.org\/index.php\/wp-json\/wp\/v2\/tags?post=4274"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}