{"id":4344,"date":"2024-04-21T10:39:21","date_gmt":"2024-04-21T10:39:21","guid":{"rendered":"https:\/\/aep61-74.org\/?p=4344"},"modified":"2026-05-05T11:16:58","modified_gmt":"2026-05-05T11:16:58","slug":"mudar-de-vida-jose-mario-branco-vida-e-obra-nelson-guerreiro-e-pedro-fidalgo-2","status":"publish","type":"post","link":"https:\/\/aep61-74.org\/index.php\/2024\/04\/21\/mudar-de-vida-jose-mario-branco-vida-e-obra-nelson-guerreiro-e-pedro-fidalgo-2\/","title":{"rendered":"Mudar de Vida, Jose Mario Branco &#8211; Vida e Obra &#8211; Nelson Guerreiro e Pedro Fidalgo"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"427\" src=\"https:\/\/aep61-74.org\/wp-content\/uploads\/2024\/04\/103A3283-1.jpeg\" alt=\"\" class=\"wp-image-4346\" srcset=\"https:\/\/aep61-74.org\/wp-content\/uploads\/2024\/04\/103A3283-1.jpeg 640w, https:\/\/aep61-74.org\/wp-content\/uploads\/2024\/04\/103A3283-1-300x200.jpeg 300w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/figure>\n\n\n\n<p>HOMENAGEM A JOS\u00c9 M\u00c1RIO BRANCO<\/p>\n\n\n\n<p>14 de Abril, entre as 16H00 e as 20H00<\/p>\n\n\n\n<p>TEIV-Teatro Est\u00fadio Ildefonso Val\u00e9rio em Alverca<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Esta ac\u00e7\u00e3o estava integrada no projecto \u201cC\u00e1lice do Descontentamento\u201d que a Companhia Teatral Cegadas vem realizando com o apoio da AEP 61-74.<\/p>\n\n\n\n<p>Perante a sala cheia foi exibido o filme \u201cMudar de Vida, Jos\u00e9 M\u00e1rio Branco, Vida e Obra\u201d realizado por Nelson Guerreiro e Pedro Fidalgo.<\/p>\n\n\n\n<p>No final do filme Nelson Guerreiro falou sobre a realiza\u00e7\u00e3o e respondeu a v\u00e1rias perguntas do p\u00fablico presente.<\/p>\n\n\n\n<p>Em seguida o Dr Manuel Ferreira director da base de dados do Arquivo&nbsp; Jos\u00e9 M\u00e1rio Branco, descreveu como est\u00e1 a ser organizado o arquivo e os v\u00e1rios aspectos da sua divulga\u00e7\u00e3o, respondendo a varias quest\u00f5es levantadas pelo publico presente.<\/p>\n\n\n\n<p>Interveio tamb\u00e9m Ricardo Andrade, Curador do esp\u00f3lio escrito e musical de Jos\u00e9 M\u00e1rio Branco depositado no Centro de Estudos e Documenta\u00e7\u00e3o&nbsp; JMB, M\u00fasica e Liberdade na Faculdade de Ci\u00eancias Sociais e Humanas da Universidade Nova de Lisboa, abordando a organiza\u00e7\u00e3o do esp\u00f3lio e a investiga\u00e7\u00e3o que est\u00e1 ser realizada. Respondeu a v\u00e1rias perguntas levantadas pelo p\u00fablico presente.<\/p>\n\n\n\n<p>Interveio por fim Manuel Monteiro referindo v\u00e1rios aspectos&nbsp; do percurso pol\u00edtico e c\u00edvico de Jos\u00e9 M\u00e1rio Branco, da amizade entre ambos lendo um poema que elaborou musicado por Jos\u00e9 M\u00e1rio Branco.<\/p>\n\n\n\n<p>Nesta sess\u00e3o de homenagem, Pedro Branco e Ana L\u00facia Magalh\u00e3es cantaram v\u00e1rias can\u00e7\u00f5es de Jos\u00e9 M\u00e1rio Branco.<\/p>\n\n\n\n<p>Por fim representantes da Companhia Teatral Cegadas apelaram ao p\u00fablico para participar&nbsp; no dia 27 de Abril no espet\u00e1culo que se vai realizar na Pra\u00e7a de Touros Palha Blanco em Vila Franca de Xira<\/p>\n\n\n\n<p>Manuel Rodrigues<\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\"><p>HOMENAGEM A JOS\u00c9 M\u00c1RIO BRANCO 14 de Abril, entre as 16H00 e as 20H00 TEIV-Teatro Est\u00fadio Ildefonso Val\u00e9rio em Alverca Esta ac\u00e7\u00e3o estava integrada no projecto \u201cC\u00e1lice do Descontentamento\u201d que a Companhia Teatral Cegadas vem <a class=\"mh-excerpt-more\" href=\"https:\/\/aep61-74.org\/index.php\/2024\/04\/21\/mudar-de-vida-jose-mario-branco-vida-e-obra-nelson-guerreiro-e-pedro-fidalgo-2\/\" title=\"Mudar de Vida, Jose Mario Branco &#8211; Vida e Obra &#8211; Nelson Guerreiro e Pedro Fidalgo\">[&#8230;]<\/a><\/p>\n<\/div>","protected":false},"author":1,"featured_media":4345,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[243],"tags":[],"class_list":{"0":"post-4344","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-informacoes"},"_links":{"self":[{"href":"https:\/\/aep61-74.org\/index.php\/wp-json\/wp\/v2\/posts\/4344","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aep61-74.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aep61-74.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aep61-74.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/aep61-74.org\/index.php\/wp-json\/wp\/v2\/comments?post=4344"}],"version-history":[{"count":2,"href":"https:\/\/aep61-74.org\/index.php\/wp-json\/wp\/v2\/posts\/4344\/revisions"}],"predecessor-version":[{"id":4348,"href":"https:\/\/aep61-74.org\/index.php\/wp-json\/wp\/v2\/posts\/4344\/revisions\/4348"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aep61-74.org\/index.php\/wp-json\/wp\/v2\/media\/4345"}],"wp:attachment":[{"href":"https:\/\/aep61-74.org\/index.php\/wp-json\/wp\/v2\/media?parent=4344"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aep61-74.org\/index.php\/wp-json\/wp\/v2\/categories?post=4344"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aep61-74.org\/index.php\/wp-json\/wp\/v2\/tags?post=4344"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}